{"id":12638,"date":"2025-12-15T14:07:51","date_gmt":"2025-12-15T11:07:51","guid":{"rendered":"https:\/\/salihliosb.org.tr\/?p=12638"},"modified":"2025-12-15T14:09:16","modified_gmt":"2025-12-15T11:09:16","slug":"salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi","status":"publish","type":"post","link":"https:\/\/salihliosb.org.tr\/en\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/","title":{"rendered":"SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"12638\" class=\"elementor elementor-12638\" data-elementor-post-type=\"post\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c45a88 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-row-scroll-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"0c45a88\" data-element_type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-682154a pxl-col-none pxl-column-none\" data-id=\"682154a\" data-element_type=\"column\">\r\n        <div class=\"elementor-widget-wrap\">\r\n                     \r\n                    <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-1613bc7c elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-row-scroll-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"1613bc7c\" data-element_type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-738cedb3 pxl-col-none pxl-column-none\" data-id=\"738cedb3\" data-element_type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-74087dd2 elementor-widget elementor-widget-text-editor\" data-id=\"74087dd2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.22.0 - 26-06-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h1>SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI<\/h1><p>Salihli Organize Sanayi B\u00f6lgesi (OSB) M\u00fcte\u015febbis Heyet Toplant\u0131s\u0131, Manisa Valisi ve ayn\u0131 zamanda M\u00fcte\u015febbis Heyet Ba\u015fkan\u0131m\u0131z Say\u0131n Vahdettin \u00d6ZKAN Ba\u015fkanl\u0131\u011f\u0131nda Zoom \u00fczerinden ger\u00e7ekle\u015ftirildi.<br \/>Toplant\u0131da Salihli Organize Sanayi B\u00f6lgesinde devam eden ve planlanan projeler de\u011ferlendirildi.<\/p><p>Al\u0131nan kararlar t\u00fcm sanayicilerimize ve b\u00f6lgemize\u00a0hay\u0131rl\u0131\u00a0olsun.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-de44280 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-type-header-none pxl-row-scroll-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"de44280\" data-element_type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-702976e pxl-col-none pxl-column-none\" data-id=\"702976e\" data-element_type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-7fa46ce elementor-widget elementor-widget-bdt-advanced-image-gallery\" data-id=\"7fa46ce\" data-element_type=\"widget\" data-widget_type=\"bdt-advanced-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"bdt-avdg-7fa46ce\" class=\"bdt-ep-advanced-image-gallery bdt-ep-advanced-image-gallery-skin-default jgallery\" data-jgallery-jfheight=\"260\" data-jgallery-itemgap=\"5\" data-bdt-lightbox=\"animation: slide;\" data-settings=\"{&quot;id&quot;:&quot;#bdt-avdg-7fa46ce&quot;,&quot;tiltShow&quot;:true}\">\n\t\t\t\n\t\t\t\t<div class=\"bdt-ep-advanced-image-gallery-item bdt-transition-toggle\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-image-gallery-inner\" data-tilt=\"\">\n\t\t\t\t\t\t<div class=\"bdt-ep-advanced-image-gallery-thumbnail bdt-transition-toggle\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1010\" height=\"400\" src=\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/2-2.png\" class=\"jgalleryImage\" alt=\"2\" srcset=\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/2-2.png 1010w, https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/2-2-300x119.png 300w, https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/2-2-768x304.png 768w, https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/2-2-18x7.png 18w, https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/2-2-960x380.png 960w\" sizes=\"(max-width: 1010px) 100vw, 1010px\" \/><\/div>\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-ep-advanced-image-gallery-content\">\n\t\t\t\t<div class=\"bdt-ep-advanced-image-gallery-content-inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-ep-advanced-image-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t<a class=\"bdt-ep-advanced-image-gallery-item-link elementor-clickable icon-type-icon\" data-elementor-open-lightbox=\"no\" data-caption=\"\" data-href=\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/2-2.png\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-icon-plus-2\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t<div class=\"bdt-ep-advanced-image-gallery-item bdt-transition-toggle\">\n\t\t\t\t\t<div class=\"bdt-ep-advanced-image-gallery-inner\" data-tilt=\"\">\n\t\t\t\t\t\t<div class=\"bdt-ep-advanced-image-gallery-thumbnail bdt-transition-toggle\"><img decoding=\"async\" width=\"1010\" height=\"400\" src=\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png\" class=\"jgalleryImage\" alt=\"1\" srcset=\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png 1010w, https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2-300x119.png 300w, https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2-768x304.png 768w, https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2-18x7.png 18w, https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2-960x380.png 960w\" sizes=\"(max-width: 1010px) 100vw, 1010px\" \/><\/div>\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-ep-advanced-image-gallery-content\">\n\t\t\t\t<div class=\"bdt-ep-advanced-image-gallery-content-inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-ep-advanced-image-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t<a class=\"bdt-ep-advanced-image-gallery-item-link elementor-clickable icon-type-icon\" data-elementor-open-lightbox=\"no\" data-caption=\"\" data-href=\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-icon-plus-2\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>SAL\u0130HL\u0130 OSB Y\u00d6NET\u0130M KURULUMUZ KASIM AYININ \u0130K\u0130NC\u0130 TOPLANTISINI YAPTI Salihli Organize Sanayi B\u00f6lgemizin Y\u00f6netim Kurulu, Y\u00f6netim Kurulu Ba\u015fkan\u0131m\u0131z Muhittin B\u0130LGET Ba\u015fkanl\u0131\u011f\u0131nda topland\u0131. Toplant\u0131ya; Y\u00f6netim Kurulu Ba\u015fkan Vekilimiz Yunus ER, Y\u00f6netim Kurulu \u00dcyeleri Ercan PETEKKAYA, Rasim SEL\u00c7UK ve Teoman DURUKAN kat\u0131ld\u0131. Y\u00f6netim Kurulu Toplant\u0131m\u0131zda;1. Ve 2. Etap ile ilgili konular, At\u0131ksu Ar\u0131tma Tesisi ile ilgili konular, [&hellip;]<\/p>","protected":false},"author":1,"featured_media":12639,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,22],"tags":[],"class_list":["post-12638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-duyurular","category-haberler"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.5 (Yoast SEO v24.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI - Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salihliosb.org.tr\/en\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI\" \/>\n<meta property=\"og:description\" content=\"SAL\u0130HL\u0130 OSB Y\u00d6NET\u0130M KURULUMUZ KASIM AYININ \u0130K\u0130NC\u0130 TOPLANTISINI YAPTI Salihli Organize Sanayi B\u00f6lgemizin Y\u00f6netim Kurulu, Y\u00f6netim Kurulu Ba\u015fkan\u0131m\u0131z Muhittin B\u0130LGET Ba\u015fkanl\u0131\u011f\u0131nda topland\u0131. Toplant\u0131ya; Y\u00f6netim Kurulu Ba\u015fkan Vekilimiz Yunus ER, Y\u00f6netim Kurulu \u00dcyeleri Ercan PETEKKAYA, Rasim SEL\u00c7UK ve Teoman DURUKAN kat\u0131ld\u0131. Y\u00f6netim Kurulu Toplant\u0131m\u0131zda;1. Ve 2. Etap ile ilgili konular, At\u0131ksu Ar\u0131tma Tesisi ile ilgili konular, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salihliosb.org.tr\/en\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/\" \/>\n<meta property=\"og:site_name\" content=\"Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-15T11:07:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:09:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1010\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"salihliosb.org.tr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"salihliosb.org.tr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/\"},\"author\":{\"name\":\"salihliosb.org.tr\",\"@id\":\"https:\/\/salihliosb.org.tr\/#\/schema\/person\/20a2de0811062b67d3ee5bc1c52e0295\"},\"headline\":\"SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI\",\"datePublished\":\"2025-12-15T11:07:51+00:00\",\"dateModified\":\"2025-12-15T11:09:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/\"},\"wordCount\":152,\"publisher\":{\"@id\":\"https:\/\/salihliosb.org.tr\/#organization\"},\"image\":{\"@id\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png\",\"articleSection\":[\"Duyurular\",\"Haberler\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/\",\"url\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/\",\"name\":\"SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI - Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc\",\"isPartOf\":{\"@id\":\"https:\/\/salihliosb.org.tr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png\",\"datePublished\":\"2025-12-15T11:07:51+00:00\",\"dateModified\":\"2025-12-15T11:09:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#primaryimage\",\"url\":\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png\",\"contentUrl\":\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png\",\"width\":1010,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\/\/salihliosb.org.tr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/salihliosb.org.tr\/#website\",\"url\":\"https:\/\/salihliosb.org.tr\/\",\"name\":\"Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc\",\"description\":\"Sanayiye ve B\u00f6lgeye De\u011fer Kat\u0131yoruz, Gelece\u011fi \u0130n\u015fa Ediyoruz!\",\"publisher\":{\"@id\":\"https:\/\/salihliosb.org.tr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/salihliosb.org.tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/salihliosb.org.tr\/#organization\",\"name\":\"Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc\",\"url\":\"https:\/\/salihliosb.org.tr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/salihliosb.org.tr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2024\/09\/cropped-logo-400.png\",\"contentUrl\":\"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2024\/09\/cropped-logo-400.png\",\"width\":512,\"height\":512,\"caption\":\"Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc\"},\"image\":{\"@id\":\"https:\/\/salihliosb.org.tr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/salihliosb.org.tr\/#\/schema\/person\/20a2de0811062b67d3ee5bc1c52e0295\",\"name\":\"salihliosb.org.tr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/salihliosb.org.tr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/salihliosb.org.tr\/wp-content\/litespeed\/avatar\/024fa5c72965f6026a62b8db1766b29c.jpg?ver=1778171051\",\"contentUrl\":\"https:\/\/salihliosb.org.tr\/wp-content\/litespeed\/avatar\/024fa5c72965f6026a62b8db1766b29c.jpg?ver=1778171051\",\"caption\":\"salihliosb.org.tr\"},\"sameAs\":[\"https:\/\/salihliosb.org.tr\"],\"url\":\"https:\/\/salihliosb.org.tr\/en\/author\/darkgoldenrod-curlew-677796-hostingersite-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI - Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salihliosb.org.tr\/en\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/","og_locale":"en_US","og_type":"article","og_title":"SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI","og_description":"SAL\u0130HL\u0130 OSB Y\u00d6NET\u0130M KURULUMUZ KASIM AYININ \u0130K\u0130NC\u0130 TOPLANTISINI YAPTI Salihli Organize Sanayi B\u00f6lgemizin Y\u00f6netim Kurulu, Y\u00f6netim Kurulu Ba\u015fkan\u0131m\u0131z Muhittin B\u0130LGET Ba\u015fkanl\u0131\u011f\u0131nda topland\u0131. Toplant\u0131ya; Y\u00f6netim Kurulu Ba\u015fkan Vekilimiz Yunus ER, Y\u00f6netim Kurulu \u00dcyeleri Ercan PETEKKAYA, Rasim SEL\u00c7UK ve Teoman DURUKAN kat\u0131ld\u0131. Y\u00f6netim Kurulu Toplant\u0131m\u0131zda;1. Ve 2. Etap ile ilgili konular, At\u0131ksu Ar\u0131tma Tesisi ile ilgili konular, [&hellip;]","og_url":"https:\/\/salihliosb.org.tr\/en\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/","og_site_name":"Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc","article_published_time":"2025-12-15T11:07:51+00:00","article_modified_time":"2025-12-15T11:09:16+00:00","og_image":[{"width":1010,"height":400,"url":"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png","type":"image\/png"}],"author":"salihliosb.org.tr","twitter_card":"summary_large_image","twitter_misc":{"Written by":"salihliosb.org.tr","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#article","isPartOf":{"@id":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/"},"author":{"name":"salihliosb.org.tr","@id":"https:\/\/salihliosb.org.tr\/#\/schema\/person\/20a2de0811062b67d3ee5bc1c52e0295"},"headline":"SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI","datePublished":"2025-12-15T11:07:51+00:00","dateModified":"2025-12-15T11:09:16+00:00","mainEntityOfPage":{"@id":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/"},"wordCount":152,"publisher":{"@id":"https:\/\/salihliosb.org.tr\/#organization"},"image":{"@id":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#primaryimage"},"thumbnailUrl":"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png","articleSection":["Duyurular","Haberler"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/","url":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/","name":"SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI - Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc","isPartOf":{"@id":"https:\/\/salihliosb.org.tr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#primaryimage"},"image":{"@id":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#primaryimage"},"thumbnailUrl":"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png","datePublished":"2025-12-15T11:07:51+00:00","dateModified":"2025-12-15T11:09:16+00:00","breadcrumb":{"@id":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#primaryimage","url":"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png","contentUrl":"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2025\/12\/1-2.png","width":1010,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/salihliosb.org.tr\/salihli-osb-mutesebbis-heyetimiz-vali-vahdettin-ozkan-baskanliginda-toplandi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/salihliosb.org.tr\/"},{"@type":"ListItem","position":2,"name":"SAL\u0130HL\u0130 OSB M\u00dcTE\u015eEBB\u0130S HEYET\u0130M\u0130Z VAL\u0130 VAHDETT\u0130N \u00d6ZKAN BA\u015eKANLI\u011eINDA TOPLANDI"}]},{"@type":"WebSite","@id":"https:\/\/salihliosb.org.tr\/#website","url":"https:\/\/salihliosb.org.tr\/","name":"Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc","description":"Sanayiye ve B\u00f6lgeye De\u011fer Kat\u0131yoruz, Gelece\u011fi \u0130n\u015fa Ediyoruz!","publisher":{"@id":"https:\/\/salihliosb.org.tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salihliosb.org.tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/salihliosb.org.tr\/#organization","name":"Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc","url":"https:\/\/salihliosb.org.tr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/salihliosb.org.tr\/#\/schema\/logo\/image\/","url":"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2024\/09\/cropped-logo-400.png","contentUrl":"https:\/\/salihliosb.org.tr\/wp-content\/uploads\/2024\/09\/cropped-logo-400.png","width":512,"height":512,"caption":"Salihli Organize Sanayi B\u00f6lgesi M\u00fcd\u00fcrl\u00fc\u011f\u00fc"},"image":{"@id":"https:\/\/salihliosb.org.tr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/salihliosb.org.tr\/#\/schema\/person\/20a2de0811062b67d3ee5bc1c52e0295","name":"salihliosb.org.tr","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/salihliosb.org.tr\/#\/schema\/person\/image\/","url":"https:\/\/salihliosb.org.tr\/wp-content\/litespeed\/avatar\/024fa5c72965f6026a62b8db1766b29c.jpg?ver=1778171051","contentUrl":"https:\/\/salihliosb.org.tr\/wp-content\/litespeed\/avatar\/024fa5c72965f6026a62b8db1766b29c.jpg?ver=1778171051","caption":"salihliosb.org.tr"},"sameAs":["https:\/\/salihliosb.org.tr"],"url":"https:\/\/salihliosb.org.tr\/en\/author\/darkgoldenrod-curlew-677796-hostingersite-com\/"}]}},"_links":{"self":[{"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/posts\/12638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/comments?post=12638"}],"version-history":[{"count":4,"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/posts\/12638\/revisions"}],"predecessor-version":[{"id":12645,"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/posts\/12638\/revisions\/12645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/media\/12639"}],"wp:attachment":[{"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/media?parent=12638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/categories?post=12638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salihliosb.org.tr\/en\/wp-json\/wp\/v2\/tags?post=12638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}